{"id":17237,"date":"2019-11-26T20:37:47","date_gmt":"2019-11-27T02:37:47","guid":{"rendered":"https:\/\/www.wrighttouchdesigngroup.com\/lern\/?page_id=17237"},"modified":"2021-08-19T17:56:03","modified_gmt":"2021-08-19T22:56:03","slug":"william-draves","status":"publish","type":"page","link":"https:\/\/lern.com\/lerntest\/william-draves\/","title":{"rendered":"William Draves"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-17237","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lern.com\/lerntest\/wp-json\/wp\/v2\/pages\/17237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lern.com\/lerntest\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lern.com\/lerntest\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lern.com\/lerntest\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lern.com\/lerntest\/wp-json\/wp\/v2\/comments?post=17237"}],"version-history":[{"count":4,"href":"https:\/\/lern.com\/lerntest\/wp-json\/wp\/v2\/pages\/17237\/revisions"}],"predecessor-version":[{"id":17552,"href":"https:\/\/lern.com\/lerntest\/wp-json\/wp\/v2\/pages\/17237\/revisions\/17552"}],"wp:attachment":[{"href":"https:\/\/lern.com\/lerntest\/wp-json\/wp\/v2\/media?parent=17237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}